{"id":11085,"date":"2023-08-15T18:47:51","date_gmt":"2023-08-15T18:47:51","guid":{"rendered":"https:\/\/spiroflow1.wpengine.com\/?post_type=case-study&#038;p=11085"},"modified":"2023-08-15T18:47:51","modified_gmt":"2023-08-15T18:47:51","slug":"aeromechanische-forderer-sweet-success-africa","status":"publish","type":"case-study","link":"https:\/\/www.spiroflow.com\/de\/fallstudie\/aeromechanische-forderer-sweet-success-africa\/","title":{"rendered":"Aeromechanische F\u00f6rderer ein gro\u00dfer Erfolg in Afrika"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Kundenanforderungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Kasapreko aus Baatsonaa, Accra, produziert die bekannten \u201eAlomo Bitters\u201c \u2013 die authentischen afrikanischen Kr\u00e4uterbitter. Es wird aus sorgf\u00e4ltig ausgew\u00e4hlten tropischen Pflanzenextrakten hergestellt, die f\u00fcr ihre nachgewiesene medizinische Wirkung bekannt sind. Es hat seine Wurzeln in der traditionellen Kr\u00e4uterheilkunde \u2013 sorgf\u00e4ltig erforscht vom Centre for Scientific Research into Plant Medicine mit Sitz in Ghana \u2013 einer Tochtergesellschaft der Weltgesundheitsorganisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund der gesteigerten Sirupproduktion von Kasapreko von 1.000 Litern pro Schicht auf 10.000 Liter pro Schicht war Spiroflows Aero Mechanical Coveyor erforderlich, um die Effizienz und Geschwindigkeit der Beladung des Mischtanks mit Zucker zu verbessern.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Spiroflow-L\u00f6sung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Herr Edmond Blankson, General Manager \u2013 Plant &amp; Bottling, best\u00e4tigt; \u201eDer aeromechanische F\u00f6rderer hat nicht nur dazu beigetragen, die Produktion zu steigern, sondern hat auch die Handhabung des Zuckers zu einem hygienischeren Vorgang gemacht.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das an Kasapreko gelieferte F\u00f6rderband besteht aus Edelstahl mit einem \u201erund um die Ecke\u201c-Design. Er f\u00f6rdert Zucker 15,5 Fu\u00df\/4,7 m vertikal und 6,5 Fu\u00df\/2 m horizontal in einer einzigen Einheit, die am Auslass angetrieben wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Zucker wird \u00fcber einen Sacktrichter am Einlass in den F\u00f6rderer geladen. Der Trichter verf\u00fcgt \u00fcber ein Sicherheitsgitter, in das die Beutel beim Aufschneiden abgelegt werden k\u00f6nnen. Dies geschieht in einem Staubschrank und durch einen durchsichtigen Streifenvorhang aus Kunststoff. Der Schrank ist mit einem Stutzen ausgestattet, so dass er an eine zentrale Staubabsauganlage angeschlossen werden kann, um eine saubere und sichere Arbeitsumgebung zu gew\u00e4hrleisten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut Herrn Blankson hat der \u00f6rtliche Vertreter von Spiroflow \u201eden Auftrag gewonnen, weil Spiroflow lokalen Kundendienst und lokale Beratung bei der Auswahl der Ausr\u00fcstung f\u00fcr die erh\u00f6hte Fabrikkapazit\u00e4t bietet.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein aeromechanischer F\u00f6rderer ist in der Lage, gro\u00dfe Materialmengen in jedem Winkel ohne Effizienzverluste zu bewegen. Scheiben, die mit einem Seil verbunden sind, das sich mit hoher Geschwindigkeit in einem geschlossenen Zu- und R\u00fccklaufrohrsystem bewegt, rei\u00dfen das Produkt in ihren Windschatten mit. Dem System wird keine Luft hinzugef\u00fcgt oder entzogen, sodass keine Luftfilterung erforderlich ist. Sie sind die ideale Wahl f\u00fcr Anwendungen, die einen \u201evollst\u00e4ndigen Chargentransfer\u201c abgemessener Materialmengen erfordern. Der neue, optionale automatische Kabelspanner DART bietet ein automatisches Einlaufen, was den Wartungsaufwand reduziert und die Lebensdauer des F\u00f6rderkabels erheblich verl\u00e4ngert.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"\/wp-content\/uploads\/2023\/08\/1017-Aero-Mechanical-Conveyor-Sugar-Kasapreko.pdf\" style=\"background-color:#f47121\" target=\"_blank\" rel=\"noreferrer noopener\">Fallstudie als PDF herunterladen<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Kundenanforderungen Kasapreko aus Baatsonaa, Accra, produziert die bekannten \u201eAlomo Bitters\u201c \u2013 die authentischen afrikanischen Kr\u00e4uterbitter. Es wird aus sorgf\u00e4ltig ausgew\u00e4hlten tropischen Pflanzenextrakten hergestellt, die f\u00fcr ihre nachgewiesene medizinische Wirkung bekannt sind. Es hat seine Wurzeln in der traditionellen Kr\u00e4utermedizin \u2013 sorgf\u00e4ltig erforscht vom in Ghana ans\u00e4ssigen Zentrum f\u00fcr wissenschaftliche Pflanzenforschung [\u2026]<\/p>","protected":false},"featured_media":60,"menu_order":0,"template":"","case-study-category":[],"class_list":["post-11085","case-study","type-case-study","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.spiroflow.com\/de\/wp-json\/wp\/v2\/case-study\/11085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spiroflow.com\/de\/wp-json\/wp\/v2\/case-study"}],"about":[{"href":"https:\/\/www.spiroflow.com\/de\/wp-json\/wp\/v2\/types\/case-study"}],"version-history":[{"count":0,"href":"https:\/\/www.spiroflow.com\/de\/wp-json\/wp\/v2\/case-study\/11085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spiroflow.com\/de\/wp-json\/wp\/v2\/media\/60"}],"wp:attachment":[{"href":"https:\/\/www.spiroflow.com\/de\/wp-json\/wp\/v2\/media?parent=11085"}],"wp:term":[{"taxonomy":"case-study-category","embeddable":true,"href":"https:\/\/www.spiroflow.com\/de\/wp-json\/wp\/v2\/case-study-category?post=11085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}